{"id":5497,"date":"2026-06-22T16:57:13","date_gmt":"2026-06-22T14:57:13","guid":{"rendered":"https:\/\/forkommerce.com\/prodotto\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/"},"modified":"2026-07-10T10:16:24","modified_gmt":"2026-07-10T08:16:24","slug":"batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah","status":"publish","type":"product","link":"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/","title":{"rendered":"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah"},"content":{"rendered":"<p>Das COMPACT 3000 ist ein professionelles Drehstrom-Ladeger\u00e4t f\u00fcr das Laden von Blei-Traktionsbatterien f\u00fcr Gabelstapler \/ Arbeitsb\u00fchnen \/ Industriereinigungsmaschinen.<\/p>\n<p>Hauptmerkmale:<\/p>\n<ul>\n<li>Wiederaufladbare Batterien: Kapazit\u00e4t von 750 Ah bis 875 Ah<\/li>\n<li>Abmessungen: cm 47 x cm 46,5 xcm\u00a0 70 h<\/li>\n<li>Drehstromversorgung 3x400V oder 3x220V (Einphasenversion auf Anfrage erh\u00e4ltlich)<\/li>\n<li>Elektronische Mikroprozessorsteuerung f\u00fcr intelligentes Lademanagement<\/li>\n<li>Tropenfester Dreiphasen-Transformator (Stern-Dreieck) mit Wicklungen der Klasse H<\/li>\n<li>Dreiphasen-Gleichrichterbr\u00fccke mit Siliziumdioden und nat\u00fcrlicher K\u00fchlung<\/li>\n<li>Einstellung der Schwellenspannung von 2,3 bis 2,4 V\/Zelle<\/li>\n<li>Einstellung der Endladung von 90 bis 210 Minuten<\/li>\n<li>Zeitgesteuerte Ausgleichsladefunktion<\/li>\n<li>LED-Anzeige der Ladephasen und eventueller St\u00f6rungen<\/li>\n<li>Automatische Abschaltung des Ladeger\u00e4ts bei abgeklemmter Batterie<\/li>\n<li>Blechgeh\u00e4use mit abnehmbaren Paneelen zur Erleichterung von Wartung und Service<\/li>\n<li>Epoxid-Pulverbeschichtung in Standardfarbe Rot RAL 2002<\/li>\n<li>Konformit\u00e4t mit EMV-Richtlinien und CE-Kennzeichnung<\/li>\n<\/ul>\n<p>Verf\u00fcgbare Optionen:<br \/>\nMontage von Batteriesteckern auf Anfrage<\/p>\n<p>Das Ladeger\u00e4t COMPACT 3000 stellt die ideale L\u00f6sung f\u00fcr Unternehmen, Lager, Gabelstapler und industrielle Anwendungen dar, die Zuverl\u00e4ssigkeit, Sicherheit und hohe Leistung bei der Verwaltung von Bleibatterien erfordern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah<\/p>\n","protected":false},"featured_media":5436,"template":"","meta":[],"product_brand":[],"product_cat":[312,287],"product_tag":[],"class_list":["post-5497","product","type-product","status-publish","has-post-thumbnail","product_cat-batterieladegerat-50hz-dreiphasig","product_cat-batterieladegerate-fur-gabelstapler-und-flurforderzeuge","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah | Forkommerce Spare Parts<\/title>\n<meta name=\"description\" content=\"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah f\u00fcr Gabelstapler, Arbeitsb\u00fchnen und Reinigungsmaschinen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah | Forkommerce Spare Parts\" \/>\n<meta property=\"og:description\" content=\"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah f\u00fcr Gabelstapler, Arbeitsb\u00fchnen und Reinigungsmaschinen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/\" \/>\n<meta property=\"og:site_name\" content=\"Forkommerce Spare Parts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-10T08:16:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"242\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\\\/\",\"name\":\"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah | Forkommerce Spare Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Carica-Batterie-50Hz-Trifase.jpeg\",\"datePublished\":\"2026-06-22T14:57:13+00:00\",\"dateModified\":\"2026-07-10T08:16:24+00:00\",\"description\":\"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah f\u00fcr Gabelstapler, Arbeitsb\u00fchnen und Reinigungsmaschinen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Carica-Batterie-50Hz-Trifase.jpeg\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Carica-Batterie-50Hz-Trifase.jpeg\",\"width\":242,\"height\":479,\"caption\":\"Batterieladeger\u00e4t 50 Hz dreiphasig\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"name\":\"Forkommerce Spare Parts\",\"description\":\"Ricambi originali e compatibili per carrelli elevatori e transpallet\",\"publisher\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\"},\"alternateName\":\"Forkommerce Spare Parts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\",\"name\":\"Forkommerce Spare Parts\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"width\":470,\"height\":120,\"caption\":\"Forkommerce Spare Parts\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah | Forkommerce Spare Parts","description":"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah f\u00fcr Gabelstapler, Arbeitsb\u00fchnen und Reinigungsmaschinen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/","og_locale":"de_DE","og_type":"article","og_title":"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah | Forkommerce Spare Parts","og_description":"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah f\u00fcr Gabelstapler, Arbeitsb\u00fchnen und Reinigungsmaschinen","og_url":"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/","og_site_name":"Forkommerce Spare Parts","article_modified_time":"2026-07-10T08:16:24+00:00","og_image":[{"width":242,"height":479,"url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/","url":"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/","name":"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah | Forkommerce Spare Parts","isPartOf":{"@id":"https:\/\/forkommerce.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/#primaryimage"},"image":{"@id":"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/#primaryimage"},"thumbnailUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase.jpeg","datePublished":"2026-06-22T14:57:13+00:00","dateModified":"2026-07-10T08:16:24+00:00","description":"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah f\u00fcr Gabelstapler, Arbeitsb\u00fchnen und Reinigungsmaschinen","breadcrumb":{"@id":"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/#primaryimage","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase.jpeg","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase.jpeg","width":242,"height":479,"caption":"Batterieladeger\u00e4t 50 Hz dreiphasig"},{"@type":"BreadcrumbList","@id":"https:\/\/forkommerce.com\/de\/produkt\/batterieladegeraet-50hz-drehstrom-36v-140a-compact-3000-fuer-blei-traktionsbatterien-750-875ah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/forkommerce.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/forkommerce.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Batterieladeger\u00e4t 50Hz Drehstrom 36V 140A COMPACT 3000 f\u00fcr Blei-Traktionsbatterien 750-875Ah"}]},{"@type":"WebSite","@id":"https:\/\/forkommerce.com\/it\/#website","url":"https:\/\/forkommerce.com\/it\/","name":"Forkommerce Spare Parts","description":"Ricambi originali e compatibili per carrelli elevatori e transpallet","publisher":{"@id":"https:\/\/forkommerce.com\/it\/#organization"},"alternateName":"Forkommerce Spare Parts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forkommerce.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/forkommerce.com\/it\/#organization","name":"Forkommerce Spare Parts","url":"https:\/\/forkommerce.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","width":470,"height":120,"caption":"Forkommerce Spare Parts"},"image":{"@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/product\/5497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/media\/5436"}],"wp:attachment":[{"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/media?parent=5497"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/product_brand?post=5497"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/product_cat?post=5497"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/product_tag?post=5497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}