{"id":5856,"date":"2026-07-13T15:16:58","date_gmt":"2026-07-13T13:16:58","guid":{"rendered":"https:\/\/forkommerce.com\/prodotto\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/"},"modified":"2026-07-13T15:16:58","modified_gmt":"2026-07-13T13:16:58","slug":"einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah","status":"publish","type":"product","link":"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/","title":{"rendered":"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A f\u00fcr Bleibatterien 145\u2013180 Ah"},"content":{"rendered":"<p><strong>Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A<\/strong>, entwickelt f\u00fcr das Laden von Blei-Traktionsbatterien mit einer Kapazit\u00e4t von <strong>145 Ah bis 180 Ah. <\/strong>Die HF-Technologie garantiert hohe Effizienz, Zuverl\u00e4ssigkeit und kompakte Abmessungen.<\/p>\n<p><strong>Hauptmerkmale:<\/strong><\/p>\n<ul>\n<li>Bleibatterien von <strong>145 Ah bis 180 Ah<\/strong><\/li>\n<li>Ausgangsspannung: <strong>24 V<\/strong><\/li>\n<li>Ladestrom: <strong>30 A<\/strong><\/li>\n<li><strong>Einphasige<\/strong> Stromversorgung<\/li>\n<li><strong>Hochfrequenz-Technologie (HF)<\/strong><\/li>\n<li>Kompaktes Design f\u00fcr die Wandmontage<\/li>\n<\/ul>\n<p><strong>Laden Sie das Datenblatt herunter<\/strong>, um alle Produktspezifikationen einzusehen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A<\/strong>, entwickelt f\u00fcr das Laden von Blei-Traktionsbatterien mit einer Kapazit\u00e4t von <strong>145 Ah bis 180 Ah<\/strong><\/p>\n","protected":false},"featured_media":5857,"template":"","meta":[],"product_brand":[],"product_cat":[317],"product_tag":[],"class_list":["post-5856","product","type-product","status-publish","has-post-thumbnail","product_cat-hochfrequenz-batterieladegerat","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A f\u00fcr Bleibatterien 145\u2013180 Ah | Forkommerce Spare Parts<\/title>\n<meta name=\"description\" content=\"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A, entwickelt f\u00fcr das Laden von Blei-Traktionsbatterien mit einer Kapazit\u00e4t von 145 Ah bis 180 Ah\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A f\u00fcr Bleibatterien 145\u2013180 Ah | Forkommerce Spare Parts\" \/>\n<meta property=\"og:description\" content=\"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A, entwickelt f\u00fcr das Laden von Blei-Traktionsbatterien mit einer Kapazit\u00e4t von 145 Ah bis 180 Ah\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/\" \/>\n<meta property=\"og:site_name\" content=\"Forkommerce Spare Parts\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/07\/Carica-Batterie-Alta-Frequenza-Monofase-24V-30A-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"703\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\\\/\",\"name\":\"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A f\u00fcr Bleibatterien 145\u2013180 Ah | Forkommerce Spare Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Carica-Batterie-Alta-Frequenza-Monofase-24V-30A-.jpeg\",\"datePublished\":\"2026-07-13T13:16:58+00:00\",\"description\":\"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A, entwickelt f\u00fcr das Laden von Blei-Traktionsbatterien mit einer Kapazit\u00e4t von 145 Ah bis 180 Ah\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Carica-Batterie-Alta-Frequenza-Monofase-24V-30A-.jpeg\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Carica-Batterie-Alta-Frequenza-Monofase-24V-30A-.jpeg\",\"width\":703,\"height\":451,\"caption\":\"Hochfrequenz-Ladeger\u00e4t Einphasig 24V 30A\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/produkt\\\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A f\u00fcr Bleibatterien 145\u2013180 Ah\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"name\":\"Forkommerce Spare Parts\",\"description\":\"Ricambi originali e compatibili per carrelli elevatori e transpallet\",\"publisher\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\"},\"alternateName\":\"Forkommerce Spare Parts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\",\"name\":\"Forkommerce Spare Parts\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"width\":470,\"height\":120,\"caption\":\"Forkommerce Spare Parts\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A f\u00fcr Bleibatterien 145\u2013180 Ah | Forkommerce Spare Parts","description":"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A, entwickelt f\u00fcr das Laden von Blei-Traktionsbatterien mit einer Kapazit\u00e4t von 145 Ah bis 180 Ah","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/","og_locale":"de_DE","og_type":"article","og_title":"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A f\u00fcr Bleibatterien 145\u2013180 Ah | Forkommerce Spare Parts","og_description":"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A, entwickelt f\u00fcr das Laden von Blei-Traktionsbatterien mit einer Kapazit\u00e4t von 145 Ah bis 180 Ah","og_url":"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/","og_site_name":"Forkommerce Spare Parts","og_image":[{"width":703,"height":451,"url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/07\/Carica-Batterie-Alta-Frequenza-Monofase-24V-30A-.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/","url":"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/","name":"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A f\u00fcr Bleibatterien 145\u2013180 Ah | Forkommerce Spare Parts","isPartOf":{"@id":"https:\/\/forkommerce.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/#primaryimage"},"image":{"@id":"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/#primaryimage"},"thumbnailUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/07\/Carica-Batterie-Alta-Frequenza-Monofase-24V-30A-.jpeg","datePublished":"2026-07-13T13:16:58+00:00","description":"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A, entwickelt f\u00fcr das Laden von Blei-Traktionsbatterien mit einer Kapazit\u00e4t von 145 Ah bis 180 Ah","breadcrumb":{"@id":"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/#primaryimage","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/07\/Carica-Batterie-Alta-Frequenza-Monofase-24V-30A-.jpeg","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/07\/Carica-Batterie-Alta-Frequenza-Monofase-24V-30A-.jpeg","width":703,"height":451,"caption":"Hochfrequenz-Ladeger\u00e4t Einphasig 24V 30A"},{"@type":"BreadcrumbList","@id":"https:\/\/forkommerce.com\/de\/produkt\/einphasiges-hochfrequenz-ladegeraet-24-v-30-a-fuer-bleibatterien-145-180-ah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/forkommerce.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/forkommerce.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Einphasiges Hochfrequenz-Ladeger\u00e4t 24 V 30 A f\u00fcr Bleibatterien 145\u2013180 Ah"}]},{"@type":"WebSite","@id":"https:\/\/forkommerce.com\/it\/#website","url":"https:\/\/forkommerce.com\/it\/","name":"Forkommerce Spare Parts","description":"Ricambi originali e compatibili per carrelli elevatori e transpallet","publisher":{"@id":"https:\/\/forkommerce.com\/it\/#organization"},"alternateName":"Forkommerce Spare Parts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forkommerce.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/forkommerce.com\/it\/#organization","name":"Forkommerce Spare Parts","url":"https:\/\/forkommerce.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","width":470,"height":120,"caption":"Forkommerce Spare Parts"},"image":{"@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/product\/5856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/media\/5857"}],"wp:attachment":[{"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/media?parent=5856"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/product_brand?post=5856"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/product_cat?post=5856"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/forkommerce.com\/de\/wp-json\/wp\/v2\/product_tag?post=5856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}