{"id":3100,"date":"2026-02-03T08:41:51","date_gmt":"2026-02-03T07:41:51","guid":{"rendered":"https:\/\/forkommerce.com\/prodotto\/perno-de-remache-bl644-1\/"},"modified":"2026-02-03T08:41:51","modified_gmt":"2026-02-03T07:41:51","slug":"perno-de-remache-bl644-1","status":"publish","type":"product","link":"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/","title":{"rendered":"Perno de remache BL644-1"},"content":{"rendered":"<p><strong>El perno BL644 se utiliza con la cadena de mallas BL644 (ANSI BL-Series \/ ISO LH1244) con combinaci\u00f3n 4&#215;4 y paso de 3\/4\u2033 (19,05 mm).<\/strong><\/p>\n<p><strong>Este tipo de cadena se utiliza en aplicaciones de elevaci\u00f3n y manipulaci\u00f3n de cargas pesadas (como carretillas elevadoras, elevadores, contrapesos, etc.). <\/strong><\/p>\n<p><strong>     <\/strong><\/p>\n<p><strong> Dimensiones principales<\/strong><\/p>\n<ul>\n<li><strong>Di\u00e1metro del perno (Pin Diameter): 0,312\u2033 \u2248 7,94 mm <\/strong><\/li>\n<li><strong>Longitud total del perno (pin length): aprox. 1,173\u2033 \u2248 29,8\u201330,8 mm <\/strong><\/li>\n<li><strong>Paso de la cadena (pitch): 0,750\u2033 \u2248 19,05 mm <\/strong><\/li>\n<li><strong>Espesor de la placa: aprox. 0,125\u20130,130\u2033 \u2248 3,20\u20133,30 mm <\/strong><\/li>\n<li><strong>Altura de la placa: aprox. 0,710\u20130,713\u2033 \u2248 18,1 mm<\/strong><\/li>\n<\/ul>\n<p><strong> <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Perno de remache BL644-1<\/p>\n","protected":false},"featured_media":2974,"template":"","meta":[],"product_brand":[],"product_cat":[208],"product_tag":[],"class_list":["post-3100","product","type-product","status-publish","has-post-thumbnail","product_cat-pasadores-de-cadena","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perno de remache BL644-1 | Forkommerce Spare Parts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perno de remache BL644-1 | Forkommerce Spare Parts\" \/>\n<meta property=\"og:description\" content=\"Perno de remache BL644-1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Forkommerce Spare Parts\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/02\/Perno-a-chiodo-per-catena-BL644.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"465\" \/>\n\t<meta property=\"og:image:height\" content=\"469\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/perno-de-remache-bl644-1\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/perno-de-remache-bl644-1\\\/\",\"name\":\"Perno de remache BL644-1 | Forkommerce Spare Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/perno-de-remache-bl644-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/perno-de-remache-bl644-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Perno-a-chiodo-per-catena-BL644.jpeg\",\"datePublished\":\"2026-02-03T07:41:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/perno-de-remache-bl644-1\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/perno-de-remache-bl644-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/perno-de-remache-bl644-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Perno-a-chiodo-per-catena-BL644.jpeg\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Perno-a-chiodo-per-catena-BL644.jpeg\",\"width\":465,\"height\":469,\"caption\":\"Perno remachado para cadena BL644\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/perno-de-remache-bl644-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Perno de remache BL644-1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"name\":\"Forkommerce Spare Parts\",\"description\":\"Ricambi originali e compatibili per carrelli elevatori e transpallet\",\"publisher\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\"},\"alternateName\":\"Forkommerce Spare Parts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\",\"name\":\"Forkommerce Spare Parts\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"width\":470,\"height\":120,\"caption\":\"Forkommerce Spare Parts\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perno de remache BL644-1 | Forkommerce Spare Parts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/","og_locale":"es_ES","og_type":"article","og_title":"Perno de remache BL644-1 | Forkommerce Spare Parts","og_description":"Perno de remache BL644-1","og_url":"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/","og_site_name":"Forkommerce Spare Parts","og_image":[{"width":465,"height":469,"url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/02\/Perno-a-chiodo-per-catena-BL644.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/","url":"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/","name":"Perno de remache BL644-1 | Forkommerce Spare Parts","isPartOf":{"@id":"https:\/\/forkommerce.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/#primaryimage"},"image":{"@id":"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/#primaryimage"},"thumbnailUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/02\/Perno-a-chiodo-per-catena-BL644.jpeg","datePublished":"2026-02-03T07:41:51+00:00","breadcrumb":{"@id":"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/#primaryimage","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/02\/Perno-a-chiodo-per-catena-BL644.jpeg","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/02\/Perno-a-chiodo-per-catena-BL644.jpeg","width":465,"height":469,"caption":"Perno remachado para cadena BL644"},{"@type":"BreadcrumbList","@id":"https:\/\/forkommerce.com\/es\/producto\/perno-de-remache-bl644-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/forkommerce.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/forkommerce.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Perno de remache BL644-1"}]},{"@type":"WebSite","@id":"https:\/\/forkommerce.com\/it\/#website","url":"https:\/\/forkommerce.com\/it\/","name":"Forkommerce Spare Parts","description":"Ricambi originali e compatibili per carrelli elevatori e transpallet","publisher":{"@id":"https:\/\/forkommerce.com\/it\/#organization"},"alternateName":"Forkommerce Spare Parts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forkommerce.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/forkommerce.com\/it\/#organization","name":"Forkommerce Spare Parts","url":"https:\/\/forkommerce.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","width":470,"height":120,"caption":"Forkommerce Spare Parts"},"image":{"@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/product\/3100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/media\/2974"}],"wp:attachment":[{"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/media?parent=3100"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/product_brand?post=3100"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/product_cat?post=3100"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/product_tag?post=3100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}