{"id":5393,"date":"2026-06-23T13:39:55","date_gmt":"2026-06-23T11:39:55","guid":{"rendered":"https:\/\/forkommerce.com\/prodotto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/"},"modified":"2026-07-13T11:14:50","modified_gmt":"2026-07-13T09:14:50","slug":"cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah","status":"publish","type":"product","link":"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/","title":{"rendered":"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A REVOLUTION BASIC para Bater\u00edas de Plomo de Tracci\u00f3n-M\u00e1x 600Ah"},"content":{"rendered":"<p><strong>Caracter\u00edsticas principales:<\/strong><\/p>\n<ul>\n<li>Bater\u00edas hasta <strong>600 Ah<\/strong><\/li>\n<li>Dimensiones: <strong>cm <\/strong><strong>50 \u00d7 cm 36 \u00d7 cm 45 h<\/strong><\/li>\n<li>Alimentaci\u00f3n trif\u00e1sica <strong>400 V<\/strong> (\u00b15%)<\/li>\n<li>Control electr\u00f3nico por microprocesador<\/li>\n<li>Carga con corriente decreciente (curva WA)<\/li>\n<li>Regulaci\u00f3n carga final: <strong>2,35\u20132,40 V\/elemento<\/strong><\/li>\n<li>Tiempo de carga: <strong>9\u201311 horas<\/strong><\/li>\n<li>Carga de ecualizaci\u00f3n autom\u00e1tica<\/li>\n<li>Contactor tripolar, fusible CC y protecciones t\u00e9rmicas<\/li>\n<li>Puente rectificador trif\u00e1sico con refrigeraci\u00f3n natural<\/li>\n<li>Estructura de acero galvanizado pintado en polvo<\/li>\n<li>Conforme a las normativas <strong>CE\/EMC<\/strong><\/li>\n<\/ul>\n<p><strong>Opcional:<\/strong> cable de red, cables de bater\u00eda, enchufe de red y conectores de bater\u00eda bajo pedido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A REVOLUTION BASIC para Bater\u00edas de Plomo de Tracci\u00f3n-M\u00e1x 600Ah<\/p>\n","protected":false},"featured_media":5384,"template":"","meta":[],"product_brand":[],"product_cat":[314,289],"product_tag":[],"class_list":["post-5393","product","type-product","status-publish","has-post-thumbnail","product_cat-cargador-de-bateria-50hz-trifasico","product_cat-cargadores-de-baterias-para-carretillas-elevadoras-y-montacargas","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A REVOLUTION BASIC para Bater\u00edas de Plomo de Tracci\u00f3n-M\u00e1x 600Ah | Forkommerce Spare Parts<\/title>\n<meta name=\"description\" content=\"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A para Bater\u00edas de Plomo de Tracci\u00f3n M\u00e1x 600 Ah para Carretillas elevadoras Plataformas a\u00e9reas y M\u00e1quinas de limpieza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A REVOLUTION BASIC para Bater\u00edas de Plomo de Tracci\u00f3n-M\u00e1x 600Ah | Forkommerce Spare Parts\" \/>\n<meta property=\"og:description\" content=\"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A para Bater\u00edas de Plomo de Tracci\u00f3n M\u00e1x 600 Ah para Carretillas elevadoras Plataformas a\u00e9reas y M\u00e1quinas de limpieza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/\" \/>\n<meta property=\"og:site_name\" content=\"Forkommerce Spare Parts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T09:14:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase-REVOLUTION.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"440\" \/>\n\t<meta property=\"og:image:height\" content=\"465\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\\\/\",\"name\":\"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A REVOLUTION BASIC para Bater\u00edas de Plomo de Tracci\u00f3n-M\u00e1x 600Ah | Forkommerce Spare Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Carica-Batterie-50Hz-Trifase-REVOLUTION.jpeg\",\"datePublished\":\"2026-06-23T11:39:55+00:00\",\"dateModified\":\"2026-07-13T09:14:50+00:00\",\"description\":\"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A para Bater\u00edas de Plomo de Tracci\u00f3n M\u00e1x 600 Ah para Carretillas elevadoras Plataformas a\u00e9reas y M\u00e1quinas de limpieza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Carica-Batterie-50Hz-Trifase-REVOLUTION.jpeg\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Carica-Batterie-50Hz-Trifase-REVOLUTION.jpeg\",\"width\":440,\"height\":465,\"caption\":\"Cargador de bater\u00edas trif\u00e1sico 50 Hz REVOLUTION\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/producto\\\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A REVOLUTION BASIC para Bater\u00edas de Plomo de Tracci\u00f3n-M\u00e1x 600Ah\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"name\":\"Forkommerce Spare Parts\",\"description\":\"Ricambi originali e compatibili per carrelli elevatori e transpallet\",\"publisher\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\"},\"alternateName\":\"Forkommerce Spare Parts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\",\"name\":\"Forkommerce Spare Parts\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"width\":470,\"height\":120,\"caption\":\"Forkommerce Spare Parts\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A REVOLUTION BASIC para Bater\u00edas de Plomo de Tracci\u00f3n-M\u00e1x 600Ah | Forkommerce Spare Parts","description":"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A para Bater\u00edas de Plomo de Tracci\u00f3n M\u00e1x 600 Ah para Carretillas elevadoras Plataformas a\u00e9reas y M\u00e1quinas de limpieza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/","og_locale":"es_ES","og_type":"article","og_title":"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A REVOLUTION BASIC para Bater\u00edas de Plomo de Tracci\u00f3n-M\u00e1x 600Ah | Forkommerce Spare Parts","og_description":"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A para Bater\u00edas de Plomo de Tracci\u00f3n M\u00e1x 600 Ah para Carretillas elevadoras Plataformas a\u00e9reas y M\u00e1quinas de limpieza","og_url":"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/","og_site_name":"Forkommerce Spare Parts","article_modified_time":"2026-07-13T09:14:50+00:00","og_image":[{"width":440,"height":465,"url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase-REVOLUTION.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/","url":"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/","name":"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A REVOLUTION BASIC para Bater\u00edas de Plomo de Tracci\u00f3n-M\u00e1x 600Ah | Forkommerce Spare Parts","isPartOf":{"@id":"https:\/\/forkommerce.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/#primaryimage"},"image":{"@id":"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/#primaryimage"},"thumbnailUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase-REVOLUTION.jpeg","datePublished":"2026-06-23T11:39:55+00:00","dateModified":"2026-07-13T09:14:50+00:00","description":"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A para Bater\u00edas de Plomo de Tracci\u00f3n M\u00e1x 600 Ah para Carretillas elevadoras Plataformas a\u00e9reas y M\u00e1quinas de limpieza","breadcrumb":{"@id":"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/#primaryimage","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase-REVOLUTION.jpeg","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase-REVOLUTION.jpeg","width":440,"height":465,"caption":"Cargador de bater\u00edas trif\u00e1sico 50 Hz REVOLUTION"},{"@type":"BreadcrumbList","@id":"https:\/\/forkommerce.com\/es\/producto\/cargador-de-baterias-50hz-trifasico-36v-100a-revolution-basic-para-baterias-de-plomo-de-traccion-max-600ah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/forkommerce.com\/es\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/forkommerce.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Cargador de Bater\u00edas 50Hz Trif\u00e1sico 36V 100A REVOLUTION BASIC para Bater\u00edas de Plomo de Tracci\u00f3n-M\u00e1x 600Ah"}]},{"@type":"WebSite","@id":"https:\/\/forkommerce.com\/it\/#website","url":"https:\/\/forkommerce.com\/it\/","name":"Forkommerce Spare Parts","description":"Ricambi originali e compatibili per carrelli elevatori e transpallet","publisher":{"@id":"https:\/\/forkommerce.com\/it\/#organization"},"alternateName":"Forkommerce Spare Parts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forkommerce.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/forkommerce.com\/it\/#organization","name":"Forkommerce Spare Parts","url":"https:\/\/forkommerce.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","width":470,"height":120,"caption":"Forkommerce Spare Parts"},"image":{"@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/product\/5393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/media\/5384"}],"wp:attachment":[{"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/media?parent=5393"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/product_brand?post=5393"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/product_cat?post=5393"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/forkommerce.com\/es\/wp-json\/wp\/v2\/product_tag?post=5393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}