{"id":1001,"date":"2025-04-08T09:56:53","date_gmt":"2025-04-08T07:56:53","guid":{"rendered":"https:\/\/forkommerce.com\/?page_id=1001"},"modified":"2026-06-01T08:45:20","modified_gmt":"2026-06-01T06:45:20","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/forkommerce.com\/fr\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"<h1>Politique de confidentialit\u00e9<\/h1>\n<p>La pr\u00e9sente Politique de confidentialit\u00e9 a pour objectif de d\u00e9crire les modalit\u00e9s de gestion du site en ce qui concerne le traitement des donn\u00e9es personnelles des utilisateurs\/visiteurs qui le consultent.<\/p>\n<p>Il s&#8217;agit d&#8217;une information fournie \u00e9galement en vertu de l&#8217;art. 13 du R\u00e8glement (UE) 2016\/679 (ci-apr\u00e8s \u00e9galement le \u201cR\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es\u201d ou \u201cRGPD\u201d) aux personnes qui acc\u00e8dent au site susmentionn\u00e9.<\/p>\n<p>Le site indiqu\u00e9 ci-dessus appartient \u00e0 Forkommerce. Cette information est fournie par Forkommerce exclusivement pour le site susmentionn\u00e9 et non pour d&#8217;autres sites web ou sections\/pages\/espaces appartenant \u00e0 des Tiers que l&#8217;utilisateur pourrait consulter au moyen de liens sp\u00e9cifiques.<\/p>\n<p>Les utilisateurs\/visiteurs sont invit\u00e9s \u00e0 lire attentivement la pr\u00e9sente Politique de confidentialit\u00e9 avant de fournir tout type d&#8217;information personnelle et\/ou de remplir tout formulaire \u00e9lectronique pr\u00e9sent sur le site.<\/p>\n<p><b>Index<\/b><\/p>\n<ol>\n<li><b>Responsable du traitement, Sous-traitants et Personnes autoris\u00e9es au traitement<\/b><\/li>\n<li><b>Coordonn\u00e9es du D\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (\u201cDPD\u201d)<\/b><\/li>\n<li><b>Types de donn\u00e9es trait\u00e9es, finalit\u00e9s et base juridique du traitement <\/b><\/li>\n<li><b>Destinataires des donn\u00e9es personnelles<\/b><\/li>\n<li><b>Transfert des donn\u00e9es vers des Pays tiers<\/b><\/li>\n<li><b>Modalit\u00e9s du traitement et dur\u00e9e de conservation des donn\u00e9es<\/b><\/li>\n<li><b>Droits de la Personne concern\u00e9e<\/b><\/li>\n<li><b>Communication et fourniture des donn\u00e9es<\/b><\/li>\n<li><b>Mise \u00e0 jour et modification de la Politique de confidentialit\u00e9<\/b><\/li>\n<\/ol>\n<h4 style=\"text-align: center;\">1. Responsable du traitement, Sous-traitants et Personnes autoris\u00e9es au traitement<\/h4>\n<p>Le Responsable du traitement des donn\u00e9es est<\/p>\n<blockquote><p>Forkommerce Srl<\/p><\/blockquote>\n<p>dont le si\u00e8ge social est situ\u00e9 \u00e0<\/p>\n<blockquote><p>Via Vecchia Ferriera, 13<br \/>\n36100 Vicenza (VI) &#8211; Italia<\/p><\/blockquote>\n<p>Outre les employ\u00e9s de Forkommerce (Personnes autoris\u00e9es au traitement), le traitement des donn\u00e9es pourra \u00e9galement \u00eatre effectu\u00e9 par des tiers auxquels la Soci\u00e9t\u00e9 a confi\u00e9 des activit\u00e9s sp\u00e9cifiques li\u00e9es ou instrumentales \u00e0 l&#8217;ex\u00e9cution des traitements ou \u00e0 la fourniture des services propos\u00e9s. Dans ce cas, ces m\u00eames sujets agiront en qualit\u00e9 de Responsables autonomes, de Responsables conjoints ou de Sous-traitants externes.<\/p>\n<h4 style=\"text-align: center;\">2. Coordonn\u00e9es du D\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es (\u201cDPD\u201d)<\/h4>\n<p>Le DPD d\u00e9sign\u00e9 par Forkommerce, qui repr\u00e9sentera le point de contact pour les Personnes concern\u00e9es, peut \u00eatre contact\u00e9 par les canaux suivants : e-mail : <a href=\"mailto:info@forkommerce.com\" target=\"_blank\" rel=\"noopener\">info@forkommerce.com<\/a>, courrier :<\/p>\n<blockquote><p>Forkommerce Srl<\/p><\/blockquote>\n<blockquote><p>Via Vecchia Ferriera, 13<br \/>\n36100 Vicenza (VI) &#8211; Italia<\/p><\/blockquote>\n<h4 style=\"text-align: center;\">3. Types de donn\u00e9es trait\u00e9es, finalit\u00e9s et base juridique du traitement<\/h4>\n<p><u>3.1. Donn\u00e9es de navigation<\/u> Les syst\u00e8mes informatiques et les proc\u00e9dures logicielles destin\u00e9s au fonctionnement de ce site acqui\u00e8rent, dans le cadre de leur fonctionnement normal, certaines donn\u00e9es personnelles qui sont ensuite transmises implicitement lors de l&#8217;utilisation des protocoles de communication Internet. Il s&#8217;agit d&#8217;informations qui, par leur nature, pourraient, au moyen d&#8217;associations et de traitements avec des donn\u00e9es d\u00e9tenues par des tiers, permettre d&#8217;identifier les utilisateurs\/visiteurs (par exemple adresse IP, noms de domaine des ordinateurs utilis\u00e9s par les utilisateurs\/visiteurs qui se connectent au site, etc.). Ces donn\u00e9es sont utilis\u00e9es uniquement afin d&#8217;obtenir des informations de type statistique (elles sont donc anonymes) et pour contr\u00f4ler le bon fonctionnement du site.<\/p>\n<p><u>3.2. Donn\u00e9es fournies volontairement par les utilisateurs\/visiteurs :<\/u> Lorsque les utilisateurs\/visiteurs, en se connectant \u00e0 ce site, envoient leurs donn\u00e9es personnelles pour acc\u00e9der \u00e0 certains services ou pour effectuer des demandes par courrier \u00e9lectronique, Forkommerce et\/ou les tiers avec lesquels Forkommerce pourrait fournir le service demand\u00e9 par l&#8217;utilisateur\/visiteur acquerront ces donn\u00e9es ; ces donn\u00e9es seront trait\u00e9es exclusivement pour r\u00e9pondre \u00e0 la demande ou pour fournir le service conform\u00e9ment \u00e0 la pr\u00e9sente Politique et aux informations de confidentialit\u00e9 sp\u00e9cifiques fournies lors de l&#8217;adh\u00e9sion aux diff\u00e9rents services.<\/p>\n<p><u>3.3. Finalit\u00e9s du traitement \u00e0 des fins de profilage :<\/u> Avec le consentement sp\u00e9cifique de la personne concern\u00e9e, Forkommerce pourra utiliser les donn\u00e9es fournies volontairement afin d&#8217;am\u00e9liorer les services propos\u00e9s en fonction des besoins de ses clients et afin d&#8217;obtenir des informations sur les comportements et habitudes commerciales dans le secteur sp\u00e9cifique dans lequel Forkommerce op\u00e8re. L&#8217;activit\u00e9 de profilage, concernant des personnes individuelles ou des groupes, pourrait \u00eatre r\u00e9alis\u00e9e par le traitement de donn\u00e9es d&#8217;identification du client au moyen d&#8217;une relation entre les donn\u00e9es permettant d&#8217;identifier les personnes concern\u00e9es et les indications analytiques relatives \u00e0 leur sph\u00e8re personnelle (go\u00fbts, pr\u00e9f\u00e9rences, habitudes, besoins et choix de consommation). Les donn\u00e9es seront trait\u00e9es par voie \u00e9lectronique ou t\u00e9l\u00e9matique. Les modalit\u00e9s de leur traitement seront pertinentes et non excessives par rapport au type de services fournis. Pour le traitement des donn\u00e9es destin\u00e9 au profilage, il est obligatoire d&#8217;obtenir le consentement sp\u00e9cifique et s\u00e9par\u00e9 de la personne concern\u00e9e, laquelle est d\u00e8s \u00e0 pr\u00e9sent inform\u00e9e que cette fourniture est enti\u00e8rement facultative et que tout refus n&#8217;entra\u00eenera aucune cons\u00e9quence (si ce n&#8217;est d&#8217;emp\u00eacher les traitements des donn\u00e9es destin\u00e9s au profilage).<\/p>\n<p><u>3.4. Finalit\u00e9s du traitement \u00e0 des fins de marketing direct :<\/u> Avec le consentement sp\u00e9cifique de la personne concern\u00e9e, Forkommerce pourra utiliser les donn\u00e9es fournies volontairement pour des activit\u00e9s de marketing direct, pour \u00e9laborer des \u00e9tudes, recherches et statistiques de march\u00e9 ; envoyer du mat\u00e9riel publicitaire et informatif ; effectuer des activit\u00e9s directes de vente ou de placement de produits ou de services ; envoyer des informations commerciales ; effectuer des communications commerciales interactives. Pour le traitement des donn\u00e9es destin\u00e9 \u00e0 l&#8217;exercice d&#8217;activit\u00e9s de marketing direct, il est obligatoire d&#8217;obtenir le consentement sp\u00e9cifique et s\u00e9par\u00e9 de la personne concern\u00e9e, laquelle est d\u00e8s \u00e0 pr\u00e9sent inform\u00e9e que cette fourniture est enti\u00e8rement facultative et que tout refus n&#8217;entra\u00eenera aucune cons\u00e9quence (si ce n&#8217;est d&#8217;emp\u00eacher les traitements des donn\u00e9es destin\u00e9s au marketing direct). Pour certaines formes de communication par courrier \u00e9lectronique, fax, syst\u00e8mes d&#8217;appel automatis\u00e9s et messages de type MMS ou SMS ou d&#8217;un autre type, la n\u00e9cessit\u00e9 du consentement sp\u00e9cifique et s\u00e9par\u00e9 d\u00e9coule \u00e9galement de dispositions particuli\u00e8res en mati\u00e8re de communications non sollicit\u00e9es ou de ventes \u00e0 distance. Dans ces derniers cas \u00e9galement, la fourniture est enti\u00e8rement facultative et tout refus n&#8217;entra\u00eenera aucune cons\u00e9quence (si ce n&#8217;est d&#8217;emp\u00eacher le traitement des donn\u00e9es).<\/p>\n<p>Pour les traitements vis\u00e9s aux points 3.3. et 3.4., il est pr\u00e9cis\u00e9 que la base juridique est le consentement exprim\u00e9. Pour les traitements vis\u00e9s aux points 3.1 et 3.2., la base juridique est l&#8217;ex\u00e9cution des services demand\u00e9s ou la r\u00e9ponse aux demandes des utilisateurs\/visiteurs.<\/p>\n<h4 style=\"text-align: center;\">4. Destinataires des donn\u00e9es personnelles<\/h4>\n<p>Aucune donn\u00e9e d\u00e9coulant du service web ne sera communiqu\u00e9e ou diffus\u00e9e \u00e0 des tiers, sauf pour satisfaire aux obligations pr\u00e9vues par les lois, r\u00e8glements ou normes communautaires. Les donn\u00e9es personnelles express\u00e9ment fournies par les utilisateurs\/visiteurs seront communiqu\u00e9es \u00e0 des tiers uniquement si cette communication est n\u00e9cessaire pour r\u00e9pondre aux demandes des utilisateurs\/visiteurs eux-m\u00eames, sans pr\u00e9judice de ce qui est pr\u00e9vu dans les informations sp\u00e9cifiques des diff\u00e9rents services.<\/p>\n<h4 style=\"text-align: center;\">5. Transfert des donn\u00e9es vers des Pays tiers<\/h4>\n<p>Dans le cadre des finalit\u00e9s indiqu\u00e9es \u00e0 l&#8217;art. 3 de la pr\u00e9sente information, vos donn\u00e9es personnelles ne seront pas communiqu\u00e9es\/transf\u00e9r\u00e9es \u00e0 des tiers \u00e9tablis dans des pays n&#8217;appartenant pas \u00e0 l&#8217;Union europ\u00e9enne, sous r\u00e9serve, le cas \u00e9ch\u00e9ant, de ce qui est pr\u00e9vu pour l&#8217;utilisation des Cookies, au sujet desquels il est renvoy\u00e9 \u00e0 la section correspondante du pr\u00e9sent site.<\/p>\n<h4 style=\"text-align: center;\">6. Modalit\u00e9s du traitement et dur\u00e9e de conservation des donn\u00e9es<\/h4>\n<p>Le traitement des donn\u00e9es est effectu\u00e9 au moyen d&#8217;outils automatis\u00e9s (par exemple en utilisant des proc\u00e9dures et supports \u00e9lectroniques) et\/ou manuellement (par exemple sur support papier) pendant le temps strictement n\u00e9cessaire \u00e0 la r\u00e9alisation des finalit\u00e9s pour lesquelles les donn\u00e9es ont \u00e9t\u00e9 collect\u00e9es et, en tout \u00e9tat de cause, conform\u00e9ment aux dispositions r\u00e9glementaires en vigueur en la mati\u00e8re. Les donn\u00e9es personnelles seront conserv\u00e9es pendant la dur\u00e9e strictement n\u00e9cessaire \u00e0 la poursuite des finalit\u00e9s sp\u00e9cifiques du traitement et, en particulier : &#8211; pour les donn\u00e9es indiqu\u00e9es \u00e0 l&#8217;art. 3.1., pendant le temps n\u00e9cessaire \u00e0 l&#8217;ex\u00e9cution des activit\u00e9s sp\u00e9cifi\u00e9es, sauf \u00e9ventuelles v\u00e9rifications de d\u00e9lits informatiques au pr\u00e9judice du site ; &#8211; pour les donn\u00e9es indiqu\u00e9es \u00e0 l&#8217;art. 3.2., pendant le temps n\u00e9cessaire \u00e0 l&#8217;ex\u00e9cution des services demand\u00e9s ou pour r\u00e9pondre aux demandes effectu\u00e9es, sauf \u00e9ventuelles v\u00e9rifications de d\u00e9lits informatiques au pr\u00e9judice du site ; d&#8217;\u00e9ventuels d\u00e9tails suppl\u00e9mentaires sur la conservation des donn\u00e9es concernant le service individuel ou la demande effectu\u00e9e pourront \u00eatre fournis dans les informations sp\u00e9cifiques du service individuel demand\u00e9 ; &#8211; pour les finalit\u00e9s indiqu\u00e9es \u00e0 l&#8217;art. 3.3. (profilage), pendant 12 (douze) mois \u00e0 compter du moment o\u00f9 les utilisateurs\/visiteurs donnent leur consentement sp\u00e9cifique et expr\u00e8s au traitement ; &#8211; pour les finalit\u00e9s indiqu\u00e9es \u00e0 l&#8217;art. 3.4. (marketing), pendant 24 (vingt-quatre) mois \u00e0 compter du moment o\u00f9 les utilisateurs\/visiteurs donnent leur consentement sp\u00e9cifique et expr\u00e8s au traitement.<\/p>\n<h4 style=\"text-align: center;\">7. Droits de la Personne concern\u00e9e<\/h4>\n<p>Les utilisateurs\/visiteurs pourront exercer \u00e0 tout moment les droits indiqu\u00e9s ci-dessous.<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li style=\"list-style-type: none;\">\n<ol>a. Acc\u00e8s aux donn\u00e9es personnelles : obtenir la confirmation qu&#8217;un traitement de donn\u00e9es les concernant est ou non en cours et, dans ce cas, l&#8217;acc\u00e8s aux informations suivantes : les finalit\u00e9s, les cat\u00e9gories de donn\u00e9es, les destinataires, la dur\u00e9e de conservation, le droit d&#8217;introduire une r\u00e9clamation aupr\u00e8s d&#8217;une autorit\u00e9 de contr\u00f4le, le droit de demander la rectification ou l&#8217;effacement ou la limitation du traitement ou de s&#8217;opposer au traitement lui-m\u00eame, ainsi que l&#8217;existence d&#8217;une prise de d\u00e9cision automatis\u00e9e ;<\/ol>\n<\/li>\n<li style=\"list-style-type: none;\">\n<ol>b. Demande de rectification ou d&#8217;effacement de ces donn\u00e9es ou de limitation des traitements les concernant ; par \u201climitation\u201d, on entend le marquage des donn\u00e9es conserv\u00e9es dans le but d&#8217;en limiter le traitement futur ;<\/ol>\n<\/li>\n<li style=\"list-style-type: none;\">\n<ol>c. Opposition au traitement : s&#8217;opposer, pour des motifs li\u00e9s \u00e0 leur situation particuli\u00e8re, au traitement des donn\u00e9es pour l&#8217;ex\u00e9cution d&#8217;une mission d&#8217;int\u00e9r\u00eat public ou pour la poursuite d&#8217;un int\u00e9r\u00eat l\u00e9gitime des Responsables ;<\/ol>\n<\/li>\n<li style=\"list-style-type: none;\">\n<ol>d. Portabilit\u00e9 des donn\u00e9es : en cas de traitement automatis\u00e9 effectu\u00e9 sur la base du consentement ou en ex\u00e9cution d&#8217;un contrat, recevoir dans un format structur\u00e9, couramment utilis\u00e9 et lisible par machine les donn\u00e9es les concernant ; en particulier, les donn\u00e9es seront fournies par les Responsables au format .xml, ou similaire ;<\/ol>\n<\/li>\n<li style=\"list-style-type: none;\">\n<ol>e. Retrait du consentement au traitement \u00e0 des fins de marketing, direct ou indirect, d&#8217;\u00e9tudes de march\u00e9 et de profilage ; l&#8217;exercice de ce droit ne porte en aucune mani\u00e8re atteinte \u00e0 la lic\u00e9it\u00e9 des traitements effectu\u00e9s avant le retrait ;<\/ol>\n<\/li>\n<li style=\"list-style-type: none;\">\n<ol>f. Introduire une r\u00e9clamation conform\u00e9ment \u00e0 l&#8217;art. 77 RGPD aupr\u00e8s de l&#8217;autorit\u00e9 de contr\u00f4le comp\u00e9tente selon la r\u00e9sidence habituelle, le lieu de travail ou le lieu de violation des droits ; pour l&#8217;Italie, l&#8217;autorit\u00e9 comp\u00e9tente est le Garante per la protezione dei dati personali, qui peut \u00eatre contact\u00e9 au moyen des coordonn\u00e9es indiqu\u00e9es sur le site web garanteprivacy.it<\/ol>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Les droits susmentionn\u00e9s pourront \u00eatre exerc\u00e9s en envoyant une demande sp\u00e9cifique au Responsable du traitement par les canaux de contact indiqu\u00e9s \u00e0 l&#8217;art. 1 de la pr\u00e9sente information.<\/p>\n<p>Les demandes relatives \u00e0 l&#8217;exercice des droits seront trait\u00e9es sans retard injustifi\u00e9 et, en tout \u00e9tat de cause, dans un d\u00e9lai d&#8217;un mois \u00e0 compter de la demande ; uniquement dans les cas d&#8217;une complexit\u00e9 particuli\u00e8re et du nombre de demandes, ce d\u00e9lai pourra \u00eatre prolong\u00e9 de 2 (deux) mois suppl\u00e9mentaires.<\/p>\n<h4 style=\"text-align: center;\">8. Communication et fourniture des donn\u00e9es<\/h4>\n<p>\u00c0 l&#8217;exception de ce qui est sp\u00e9cifi\u00e9 pour les donn\u00e9es vis\u00e9es \u00e0 l&#8217;art. 3.1 (donn\u00e9es de navigation, dont l&#8217;absence co\u00efncide avec l&#8217;impossibilit\u00e9 de naviguer sur le site web), les utilisateurs\/visiteurs sont libres de fournir leurs donn\u00e9es personnelles et leur non-fourniture pourra uniquement entra\u00eener l&#8217;impossibilit\u00e9 d&#8217;obtenir le service demand\u00e9.<\/p>\n<h4 style=\"text-align: center;\">9. Mise \u00e0 jour et modification de la Politique de confidentialit\u00e9<\/h4>\n<p>La pr\u00e9sente Politique de confidentialit\u00e9 peut faire l&#8217;objet de modifications au fil du temps &#8211; y compris en lien avec l&#8217;\u00e9ventuelle entr\u00e9e en vigueur de nouvelles r\u00e9glementations sectorielles, la mise \u00e0 jour ou la fourniture de nouveaux services ou encore des innovations technologiques intervenues &#8211; c&#8217;est pourquoi l&#8217;utilisateur\/visiteur est invit\u00e9 \u00e0 consulter p\u00e9riodiquement cette page.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Politique de confidentialit\u00e9 La pr\u00e9sente Politique de confidentialit\u00e9 a pour  [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-1001","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 | Forkommerce Spare Parts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forkommerce.com\/fr\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 | Forkommerce Spare Parts\" \/>\n<meta property=\"og:description\" content=\"Politique de confidentialit\u00e9 La pr\u00e9sente Politique de confidentialit\u00e9 a pour [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forkommerce.com\/fr\/politique-de-confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Forkommerce Spare Parts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T06:45:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/12\/Slider-Home.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/fr\\\/politique-de-confidentialite\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/fr\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\u00e9 | Forkommerce Spare Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\"},\"datePublished\":\"2025-04-08T07:56:53+00:00\",\"dateModified\":\"2026-06-01T06:45:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/forkommerce.com\\\/fr\\\/politique-de-confidentialite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/fr\\\/politique-de-confidentialite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"name\":\"Forkommerce Spare Parts\",\"description\":\"Ricambi originali e compatibili per carrelli elevatori e transpallet\",\"publisher\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\"},\"alternateName\":\"Forkommerce Spare Parts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\",\"name\":\"Forkommerce Spare Parts\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"width\":470,\"height\":120,\"caption\":\"Forkommerce Spare Parts\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 | Forkommerce Spare Parts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forkommerce.com\/fr\/politique-de-confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de confidentialit\u00e9 | Forkommerce Spare Parts","og_description":"Politique de confidentialit\u00e9 La pr\u00e9sente Politique de confidentialit\u00e9 a pour [...]","og_url":"https:\/\/forkommerce.com\/fr\/politique-de-confidentialite\/","og_site_name":"Forkommerce Spare Parts","article_modified_time":"2026-06-01T06:45:20+00:00","og_image":[{"width":1920,"height":800,"url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/12\/Slider-Home.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/forkommerce.com\/fr\/politique-de-confidentialite\/","url":"https:\/\/forkommerce.com\/fr\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 | Forkommerce Spare Parts","isPartOf":{"@id":"https:\/\/forkommerce.com\/it\/#website"},"datePublished":"2025-04-08T07:56:53+00:00","dateModified":"2026-06-01T06:45:20+00:00","breadcrumb":{"@id":"https:\/\/forkommerce.com\/fr\/politique-de-confidentialite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forkommerce.com\/fr\/politique-de-confidentialite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/forkommerce.com\/fr\/politique-de-confidentialite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/forkommerce.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/forkommerce.com\/it\/#website","url":"https:\/\/forkommerce.com\/it\/","name":"Forkommerce Spare Parts","description":"Ricambi originali e compatibili per carrelli elevatori e transpallet","publisher":{"@id":"https:\/\/forkommerce.com\/it\/#organization"},"alternateName":"Forkommerce Spare Parts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forkommerce.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/forkommerce.com\/it\/#organization","name":"Forkommerce Spare Parts","url":"https:\/\/forkommerce.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","width":470,"height":120,"caption":"Forkommerce Spare Parts"},"image":{"@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/forkommerce.com\/fr\/wp-json\/wp\/v2\/pages\/1001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forkommerce.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/forkommerce.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/forkommerce.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/forkommerce.com\/fr\/wp-json\/wp\/v2\/comments?post=1001"}],"version-history":[{"count":4,"href":"https:\/\/forkommerce.com\/fr\/wp-json\/wp\/v2\/pages\/1001\/revisions"}],"predecessor-version":[{"id":5192,"href":"https:\/\/forkommerce.com\/fr\/wp-json\/wp\/v2\/pages\/1001\/revisions\/5192"}],"wp:attachment":[{"href":"https:\/\/forkommerce.com\/fr\/wp-json\/wp\/v2\/media?parent=1001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}