{"id":257,"count":20,"description":"","link":"https:\/\/forkommerce.com\/it\/categoria-prodotto\/valigette-al-litio-per-transpallet-elettrici\/","name":"Valigette al litio per Transpallet elettrici","slug":"valigette-al-litio-per-transpallet-elettrici","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Valigette al litio per Transpallet elettrici Archivi | Forkommerce Spare Parts<\/title>\n<meta name=\"description\" content=\"Valigette al litio per Transpallet elettrici Linde, EP, Ameise, Caterpillar, Heli, Toyota, Mitsubishi, Cesab, Baoli, Ech\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forkommerce.com\/it\/categoria-prodotto\/valigette-al-litio-per-transpallet-elettrici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Valigette al litio per Transpallet elettrici Archivi | Forkommerce Spare Parts\" \/>\n<meta property=\"og:description\" content=\"Valigette al litio per Transpallet elettrici Linde, EP, Ameise, Caterpillar, Heli, Toyota, Mitsubishi, Cesab, Baoli, Ech\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forkommerce.com\/it\/categoria-prodotto\/valigette-al-litio-per-transpallet-elettrici\/\" \/>\n<meta property=\"og:site_name\" content=\"Forkommerce Spare Parts\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/12\/Slider-Home.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/categoria-prodotto\\\/valigette-al-litio-per-transpallet-elettrici\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/categoria-prodotto\\\/valigette-al-litio-per-transpallet-elettrici\\\/\",\"name\":\"Valigette al litio per Transpallet elettrici Archivi | Forkommerce Spare Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\"},\"description\":\"Valigette al litio per Transpallet elettrici Linde, EP, Ameise, Caterpillar, Heli, Toyota, Mitsubishi, Cesab, Baoli, Ech\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/categoria-prodotto\\\/valigette-al-litio-per-transpallet-elettrici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/categoria-prodotto\\\/valigette-al-litio-per-transpallet-elettrici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Valigette al litio per Transpallet elettrici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"name\":\"Forkommerce Spare Parts\",\"description\":\"Ricambi originali e compatibili per carrelli elevatori e transpallet\",\"publisher\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\"},\"alternateName\":\"Forkommerce Spare Parts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\",\"name\":\"Forkommerce Spare Parts\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"width\":470,\"height\":120,\"caption\":\"Forkommerce Spare Parts\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Valigette al litio per Transpallet elettrici Archivi | Forkommerce Spare Parts","description":"Valigette al litio per Transpallet elettrici Linde, EP, Ameise, Caterpillar, Heli, Toyota, Mitsubishi, Cesab, Baoli, Ech","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forkommerce.com\/it\/categoria-prodotto\/valigette-al-litio-per-transpallet-elettrici\/","og_locale":"it_IT","og_type":"article","og_title":"Valigette al litio per Transpallet elettrici Archivi | Forkommerce Spare Parts","og_description":"Valigette al litio per Transpallet elettrici Linde, EP, Ameise, Caterpillar, Heli, Toyota, Mitsubishi, Cesab, Baoli, Ech","og_url":"https:\/\/forkommerce.com\/it\/categoria-prodotto\/valigette-al-litio-per-transpallet-elettrici\/","og_site_name":"Forkommerce Spare Parts","og_image":[{"width":1920,"height":800,"url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/12\/Slider-Home.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/forkommerce.com\/it\/categoria-prodotto\/valigette-al-litio-per-transpallet-elettrici\/","url":"https:\/\/forkommerce.com\/it\/categoria-prodotto\/valigette-al-litio-per-transpallet-elettrici\/","name":"Valigette al litio per Transpallet elettrici Archivi | Forkommerce Spare Parts","isPartOf":{"@id":"https:\/\/forkommerce.com\/it\/#website"},"description":"Valigette al litio per Transpallet elettrici Linde, EP, Ameise, Caterpillar, Heli, Toyota, Mitsubishi, Cesab, Baoli, Ech","breadcrumb":{"@id":"https:\/\/forkommerce.com\/it\/categoria-prodotto\/valigette-al-litio-per-transpallet-elettrici\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/forkommerce.com\/it\/categoria-prodotto\/valigette-al-litio-per-transpallet-elettrici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/forkommerce.com\/it\/"},{"@type":"ListItem","position":2,"name":"Valigette al litio per Transpallet elettrici"}]},{"@type":"WebSite","@id":"https:\/\/forkommerce.com\/it\/#website","url":"https:\/\/forkommerce.com\/it\/","name":"Forkommerce Spare Parts","description":"Ricambi originali e compatibili per carrelli elevatori e transpallet","publisher":{"@id":"https:\/\/forkommerce.com\/it\/#organization"},"alternateName":"Forkommerce Spare Parts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forkommerce.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/forkommerce.com\/it\/#organization","name":"Forkommerce Spare Parts","url":"https:\/\/forkommerce.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","width":470,"height":120,"caption":"Forkommerce Spare Parts"},"image":{"@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/forkommerce.com\/it\/wp-json\/wp\/v2\/product_cat\/257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forkommerce.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/forkommerce.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/forkommerce.com\/it\/wp-json\/wp\/v2\/product?product_cat=257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}