{"id":5483,"date":"2026-06-22T17:04:02","date_gmt":"2026-06-22T15:04:02","guid":{"rendered":"https:\/\/forkommerce.com\/prodotto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/"},"modified":"2026-06-22T17:04:02","modified_gmt":"2026-06-22T15:04:02","slug":"carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah","status":"publish","type":"product","link":"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/","title":{"rendered":"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah"},"content":{"rendered":"<p>O COMPACT 3000 \u00e9 um carregador de baterias trif\u00e1sico profissional concebido para o carregamento de baterias de chumbo de tra\u00e7\u00e3o para Empilhadores \/ Plataformas elevat\u00f3rias \/ M\u00e1quinas de Limpeza industrial.<\/p>\n<p>Principais caracter\u00edsticas:<\/p>\n<ul>\n<li>Baterias recarreg\u00e1veis: Capacidade de 850 Ah a 960 Ah<\/li>\n<li>Dimens\u00f5es: 470 x 465 x 870 h<\/li>\n<li>Alimenta\u00e7\u00e3o trif\u00e1sica 3x400V ou 3x220V (vers\u00e3o monof\u00e1sica dispon\u00edvel sob pedido)<\/li>\n<li>Controlo eletr\u00f3nico por microprocessador para a gest\u00e3o inteligente da carga<\/li>\n<li>Transformador trif\u00e1sico estrela-tri\u00e2ngulo tropicalizado com enrolamentos em classe H<\/li>\n<li>Ponte retificadora trif\u00e1sica com d\u00edodos de sil\u00edcio e arrefecimento natural<\/li>\n<li>Regula\u00e7\u00e3o da tens\u00e3o de limiar de 2,3 a 2,4 V\/elemento<\/li>\n<li>Regula\u00e7\u00e3o da carga final de 90 a 210 minutos<\/li>\n<li>Fun\u00e7\u00e3o de carga de equaliza\u00e7\u00e3o temporizada<\/li>\n<li>Sinaliza\u00e7\u00e3o por LED das fases de carga e de eventuais anomalias<\/li>\n<li>Desconex\u00e3o autom\u00e1tica do carregador em caso de bateria desligada<\/li>\n<li>Estrutura em chapa com pain\u00e9is amov\u00edveis para facilitar a manuten\u00e7\u00e3o e assist\u00eancia<\/li>\n<li>Pintura a p\u00f3 ep\u00f3xi com cor padr\u00e3o Vermelho RAL 2002<\/li>\n<li>Conformidade com as normas EMC e marca\u00e7\u00e3o CE<\/li>\n<\/ul>\n<p>Opcionais dispon\u00edveis:<br \/>\nMontagem de conectores de bateria sob pedido<\/p>\n<p>O carregador de baterias COMPACT 3000 representa a solu\u00e7\u00e3o ideal para empresas, armaz\u00e9ns, empilhadores e aplica\u00e7\u00f5es industriais que exigem fiabilidade, seguran\u00e7a e elevado desempenho na gest\u00e3o de baterias de chumbo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah<\/p>\n","protected":false},"featured_media":5431,"template":"","meta":[],"product_brand":[],"product_cat":[313,288],"product_tag":[],"class_list":["post-5483","product","type-product","status-publish","has-post-thumbnail","product_cat-carregador-de-bateria-50hz-trifasico","product_cat-carregadores-de-baterias-para-empilhadeiras-e-veiculos-de-movimentacao-de-cargas","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah | Forkommerce Spare Parts<\/title>\n<meta name=\"description\" content=\"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah para Empilhadores Plataformas elevat\u00f3rias e M\u00e1quinas de limpeza\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah | Forkommerce Spare Parts\" \/>\n<meta property=\"og:description\" content=\"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah para Empilhadores Plataformas elevat\u00f3rias e M\u00e1quinas de limpeza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/\" \/>\n<meta property=\"og:site_name\" content=\"Forkommerce Spare Parts\" \/>\n<meta property=\"og:image\" content=\"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"242\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/pt-pt\\\/produto\\\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/pt-pt\\\/produto\\\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\\\/\",\"name\":\"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah | Forkommerce Spare Parts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/pt-pt\\\/produto\\\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/pt-pt\\\/produto\\\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Carica-Batterie-50Hz-Trifase.jpeg\",\"datePublished\":\"2026-06-22T15:04:02+00:00\",\"description\":\"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah para Empilhadores Plataformas elevat\u00f3rias e M\u00e1quinas de limpeza\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/pt-pt\\\/produto\\\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/forkommerce.com\\\/pt-pt\\\/produto\\\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/pt-pt\\\/produto\\\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Carica-Batterie-50Hz-Trifase.jpeg\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Carica-Batterie-50Hz-Trifase.jpeg\",\"width\":242,\"height\":479,\"caption\":\"Carregador de Baterias 50Hz Trif\u00e1sico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/pt-pt\\\/produto\\\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja\",\"item\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"name\":\"Forkommerce Spare Parts\",\"description\":\"Ricambi originali e compatibili per carrelli elevatori e transpallet\",\"publisher\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\"},\"alternateName\":\"Forkommerce Spare Parts\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#organization\",\"name\":\"Forkommerce Spare Parts\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"contentUrl\":\"https:\\\/\\\/forkommerce.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-Forkommercex2.png\",\"width\":470,\"height\":120,\"caption\":\"Forkommerce Spare Parts\"},\"image\":{\"@id\":\"https:\\\/\\\/forkommerce.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah | Forkommerce Spare Parts","description":"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah para Empilhadores Plataformas elevat\u00f3rias e M\u00e1quinas de limpeza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/","og_locale":"pt_PT","og_type":"article","og_title":"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah | Forkommerce Spare Parts","og_description":"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah para Empilhadores Plataformas elevat\u00f3rias e M\u00e1quinas de limpeza","og_url":"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/","og_site_name":"Forkommerce Spare Parts","og_image":[{"width":242,"height":479,"url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/","url":"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/","name":"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah | Forkommerce Spare Parts","isPartOf":{"@id":"https:\/\/forkommerce.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/#primaryimage"},"image":{"@id":"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/#primaryimage"},"thumbnailUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase.jpeg","datePublished":"2026-06-22T15:04:02+00:00","description":"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah para Empilhadores Plataformas elevat\u00f3rias e M\u00e1quinas de limpeza","breadcrumb":{"@id":"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/#primaryimage","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase.jpeg","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2026\/06\/Carica-Batterie-50Hz-Trifase.jpeg","width":242,"height":479,"caption":"Carregador de Baterias 50Hz Trif\u00e1sico"},{"@type":"BreadcrumbList","@id":"https:\/\/forkommerce.com\/pt-pt\/produto\/carregador-de-baterias-50hz-trifasico-36v-160a-compact-3000-para-baterias-de-chumbo-de-tracao-850-960ah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/forkommerce.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Loja","item":"https:\/\/forkommerce.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Carregador de Baterias 50Hz Trif\u00e1sico 36V 160A COMPACT 3000 para Baterias de Chumbo de Tra\u00e7\u00e3o 850-960Ah"}]},{"@type":"WebSite","@id":"https:\/\/forkommerce.com\/it\/#website","url":"https:\/\/forkommerce.com\/it\/","name":"Forkommerce Spare Parts","description":"Ricambi originali e compatibili per carrelli elevatori e transpallet","publisher":{"@id":"https:\/\/forkommerce.com\/it\/#organization"},"alternateName":"Forkommerce Spare Parts","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/forkommerce.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/forkommerce.com\/it\/#organization","name":"Forkommerce Spare Parts","url":"https:\/\/forkommerce.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","contentUrl":"https:\/\/forkommerce.com\/wp-content\/uploads\/2025\/09\/Logo-Forkommercex2.png","width":470,"height":120,"caption":"Forkommerce Spare Parts"},"image":{"@id":"https:\/\/forkommerce.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/forkommerce.com\/pt-pt\/wp-json\/wp\/v2\/product\/5483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forkommerce.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/forkommerce.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/forkommerce.com\/pt-pt\/wp-json\/wp\/v2\/media\/5431"}],"wp:attachment":[{"href":"https:\/\/forkommerce.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=5483"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/forkommerce.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=5483"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/forkommerce.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=5483"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/forkommerce.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=5483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}